{"id":1433,"date":"2021-07-05T23:01:49","date_gmt":"2021-07-05T23:01:49","guid":{"rendered":"https:\/\/www.frsc.utn.edu.ar\/web\/?p=1433"},"modified":"2021-07-05T23:01:49","modified_gmt":"2021-07-05T23:01:49","slug":"programa-de-becas-universitarias-cgc","status":"publish","type":"post","link":"https:\/\/www.frsc.utn.edu.ar\/web\/programa-de-becas-universitarias-cgc\/","title":{"rendered":"Programa de Becas Universitarias CGC"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>Convocatoria para R\u00edo Gallegos | 2021<\/em><\/strong> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Compa\u00f1\u00eda General de Combustibles S.A. (\u201cCGC\u201d) es una empresa dedicada a la exploraci\u00f3n y explotaci\u00f3n hidrocarbur\u00edfera, cuya operaci\u00f3n principal se desarrolla en la Cuenca Austral, Provincia de Santa Cruz, Argentina. CGC cuenta con m\u00e1s de 100 a\u00f1os de trayectoria en el rubro, posicion\u00e1ndose como una de las empresas  l\u00edderes en la industria energ\u00e9tica de Argentina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">CGC tiene el compromiso de generar un impacto positivo en su entorno, a trav\u00e9s del cual busca impulsar el desarrollo de la regi\u00f3n. Para lograr este objetivo, CGC impulsa diferentes iniciativas de inversi\u00f3n social las cuales tienen como com\u00fan denominador el desarrollo y fortalecimiento de capacidades.<br>Fundaci\u00f3n Cimientos es una organizaci\u00f3n de la sociedad civil que cuenta con m\u00e1s de 20 a\u00f1os de trayectoria promoviendo la equidad educativa mediante programas que favorecen la permanencia y el egreso de la escuela secundaria, mejoran la calidad de la educaci\u00f3n e impulsan la continuidad educativa y\/o la inserci\u00f3n laboral de j\u00f3venes que viven en contextos vulnerables.<br>En esta oportunidad CGC, Fundaci\u00f3n Cimientos y la Universidad Tecnol\u00f3gica Nacional Facultad Regional Santa Cruz (\u201cUTN FRSC\u201d) informan el inicio del Programa Becas Universitarias CGC cuyo objetivo es promover la permanencia y graduaci\u00f3n en estudios superiores, de j\u00f3venes residentes en R\u00edo Gallegos, en contextos de vulnerabilidad, desarrollando habilidades socioemocionales que favorezcan su trayectoria acad\u00e9mica y formaci\u00f3n profesional. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para m\u00e1s informaci\u00f3n ingres\u00e1 en este link para acceder a las Bases y Condiciones de postulaci\u00f3n <a rel=\"noreferrer noopener\" href=\"https:\/\/bit.ly\/2TuezSh?fbclid=IwAR2r9A6GNdFuj3kRMK23ncm3zhKNSecBHdJJUAQMBb8RoaeSZovEQpGsaME\" target=\"_blank\">https:\/\/bit.ly\/2TuezSh<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tenes tiempo hasta el 25 de julio de 2021. Postulate para recibir una nueva oportunidad de aprendizaje:<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Convocatoria para R\u00edo Gallegos | 2021 Compa\u00f1\u00eda General de Combustibles S.A. (\u201cCGC\u201d) es una empresa dedicada a la exploraci\u00f3n y explotaci\u00f3n hidrocarbur\u00edfera, cuya operaci\u00f3n principal se desarrolla en la Cuenca Austral, Provincia de Santa Cruz, Argentina. CGC cuenta con m\u00e1s de 100 a\u00f1os de trayectoria en el rubro, posicion\u00e1ndose como una de las empresas l\u00edderes [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1426,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"zakra_page_container_layout":"customizer","zakra_page_sidebar_layout":"customizer","zakra_remove_content_margin":false,"zakra_sidebar":"customizer","zakra_transparent_header":"customizer","zakra_logo":0,"zakra_main_header_style":"default","zakra_menu_item_color":"","zakra_menu_item_hover_color":"","zakra_menu_item_active_color":"","zakra_menu_active_style":"","zakra_page_header":true,"footnotes":""},"categories":[23],"tags":[],"class_list":["post-1433","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.frsc.utn.edu.ar\/web\/wp-json\/wp\/v2\/posts\/1433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.frsc.utn.edu.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.frsc.utn.edu.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.frsc.utn.edu.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.frsc.utn.edu.ar\/web\/wp-json\/wp\/v2\/comments?post=1433"}],"version-history":[{"count":1,"href":"https:\/\/www.frsc.utn.edu.ar\/web\/wp-json\/wp\/v2\/posts\/1433\/revisions"}],"predecessor-version":[{"id":1434,"href":"https:\/\/www.frsc.utn.edu.ar\/web\/wp-json\/wp\/v2\/posts\/1433\/revisions\/1434"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.frsc.utn.edu.ar\/web\/wp-json\/wp\/v2\/media\/1426"}],"wp:attachment":[{"href":"https:\/\/www.frsc.utn.edu.ar\/web\/wp-json\/wp\/v2\/media?parent=1433"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.frsc.utn.edu.ar\/web\/wp-json\/wp\/v2\/categories?post=1433"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.frsc.utn.edu.ar\/web\/wp-json\/wp\/v2\/tags?post=1433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}