{"id":1265,"date":"2021-03-25T00:09:27","date_gmt":"2021-03-25T00:09:27","guid":{"rendered":"https:\/\/www.frsc.utn.edu.ar\/web\/?p=1265"},"modified":"2021-03-25T00:09:27","modified_gmt":"2021-03-25T00:09:27","slug":"plantar-vida-y-memoria-por-los-obreros-y-companeros-desaparecidos","status":"publish","type":"post","link":"https:\/\/www.frsc.utn.edu.ar\/web\/plantar-vida-y-memoria-por-los-obreros-y-companeros-desaparecidos\/","title":{"rendered":"\u201cPlantar vida y memoria por los obreros y compa\u00f1eros desaparecidos\u201d"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El Decano de la UTN-FRSC, Lic. Sebasti\u00e1n Puig, acompa\u00f1ado por Martin y Andrea Villagra, familiares de Delmiro Segundo Villagra, desaparecido oriundo de la ciudad de R\u00edo Turbio y por&nbsp; la Ministro de Desarrollo Social de la Provincia de Santa Cruz Dra. B\u00e1rbara Weinzettel, la Secretaria de Estado de Derechos Humanos Nadia Astrada, Presidenta de Distrigas Esc Mar\u00eda Bel\u00e9n Garc\u00eda, la Presidenta del CPE Lic Mar\u00eda Cecilia Vel\u00e1zquez, la Secretaria de Estado de Desarrollo Local y Econom\u00eda Social Lic. Mar\u00eda&nbsp;<em>Agostina Mora<\/em>y funcionarios de la cartera provincial como as\u00ed tambi\u00e9n representantes de los Claustros Alumnos, Graduados, Docentes y no Docentes y funcionaros de la casa de altos estudios, al igual que en todo el pa\u00eds, procedieron a plantar un \u00e1rbol, en este caso un abedul dadas las connotaciones simb\u00f3licas de este, en el predio de la Universidad Tecnol\u00f3gica Nacional, acto que simboliza \u201cplantar memoria y sembrar futuro\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agradecido con todxs los presentes, esboz\u00f3 palabras en conmemoraci\u00f3n del d\u00eda de la Memoria, la Verdad y la Justicia en las que se recordaron a los compa\u00f1eros y trabajadores perseguidos y desaparecidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el acto, la Secretaria de Estado de Derechos Humanos, hizo entrega de pa\u00f1uelos blancos, r\u00e9plicas del hist\u00f3rico s\u00edmbolo de la lucha y reclamo de las Madres de Plaza de Mayo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Decano de la UTN-FRSC, Lic. Sebasti\u00e1n Puig, acompa\u00f1ado por Martin y Andrea Villagra, familiares de Delmiro Segundo Villagra, desaparecido oriundo de la ciudad de R\u00edo Turbio y por&nbsp; la Ministro de Desarrollo Social de la Provincia de Santa Cruz Dra. B\u00e1rbara Weinzettel, la Secretaria de Estado de Derechos Humanos Nadia Astrada, Presidenta de Distrigas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1266,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"zakra_page_container_layout":"customizer","zakra_page_sidebar_layout":"customizer","zakra_remove_content_margin":false,"zakra_sidebar":"customizer","zakra_transparent_header":"customizer","zakra_logo":0,"zakra_main_header_style":"default","zakra_menu_item_color":"","zakra_menu_item_hover_color":"","zakra_menu_item_active_color":"","zakra_menu_active_style":"","zakra_page_header":true,"footnotes":""},"categories":[23],"tags":[],"class_list":["post-1265","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.frsc.utn.edu.ar\/web\/wp-json\/wp\/v2\/posts\/1265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.frsc.utn.edu.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.frsc.utn.edu.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.frsc.utn.edu.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.frsc.utn.edu.ar\/web\/wp-json\/wp\/v2\/comments?post=1265"}],"version-history":[{"count":1,"href":"https:\/\/www.frsc.utn.edu.ar\/web\/wp-json\/wp\/v2\/posts\/1265\/revisions"}],"predecessor-version":[{"id":1267,"href":"https:\/\/www.frsc.utn.edu.ar\/web\/wp-json\/wp\/v2\/posts\/1265\/revisions\/1267"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.frsc.utn.edu.ar\/web\/wp-json\/wp\/v2\/media\/1266"}],"wp:attachment":[{"href":"https:\/\/www.frsc.utn.edu.ar\/web\/wp-json\/wp\/v2\/media?parent=1265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.frsc.utn.edu.ar\/web\/wp-json\/wp\/v2\/categories?post=1265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.frsc.utn.edu.ar\/web\/wp-json\/wp\/v2\/tags?post=1265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}